{"id":441,"date":"2010-04-06T23:30:52","date_gmt":"2010-04-06T23:30:52","guid":{"rendered":"https:\/\/kunstunterricht.ch\/e\/2010\/04\/06\/kleine-geschichte-der-piktogramme\/"},"modified":"2023-03-03T23:00:53","modified_gmt":"2023-03-03T23:00:53","slug":"kleine-geschichte-der-piktogramme","status":"publish","type":"post","link":"https:\/\/kunstunterricht.ch\/e\/kleine-geschichte-der-piktogramme\/","title":{"rendered":"Kleine Geschichte der Piktogramme"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Dieser Beitrag fasst kurz die Geschichte der Piktogramme zusammen. Angesprochen werden historische, soziale und gestalterische Aspekte.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n<table border=\"0\">\n<tbody>\n<tr>\n<td style=\"background-color: #ffffff; width: 120px;\" valign=\"middle\"><img decoding=\"async\" src=\"https:\/\/upload.wikimedia.org\/wikipedia\/commons\/6\/63\/BicycleTrailNPS1.png\" alt=\"\" width=\"99\" style=\"font-size: 11px; text-align: -webkit-center;\"><\/td>\n<td style=\"background-color: #ffffff; width: 120px;\" align=\"center\"><img decoding=\"async\" src=\"https:\/\/upload.wikimedia.org\/wikipedia\/commons\/6\/66\/No_butts_dropping.svg\" alt=\"\" width=\"111\" style=\"font-size: 11px; text-align: -webkit-center;\"><\/td>\n<td style=\"background-color: #ffffff; width: 120px;\" align=\"center\"><img decoding=\"async\" src=\"https:\/\/upload.wikimedia.org\/wikipedia\/commons\/thumb\/5\/50\/Distracted_Bicyclist_on_Cell_Phone_Crashes_into_Car_-_Yellow_Road_Caution_Sign_with_Black_Silhouettes.png\/243px-Distracted_Bicyclist_on_Cell_Phone_Crashes_into_Car_-_Yellow_Road_Caution_Sign_with_Black_Silhouettes.png\" alt=\"\" width=\"111\"><\/td>\n<td style=\"background-color: #ffffff; width: 120px;\" align=\"center\">&nbsp;<\/td>\n<td style=\"background-color: #ffffff; width: 120px;\">&nbsp;<\/td>\n<\/tr>\n<tr>\n<td style=\"background-color: #ffffff; width: 120px;\"><img decoding=\"async\" src=\"https:\/\/upload.wikimedia.org\/wikipedia\/commons\/thumb\/8\/84\/Japanese_Map_symbol_%28Lighthouse_red%29.svg\/250px-Japanese_Map_symbol_%28Lighthouse_red%29.svg.png\" alt=\"\" width=\"99\"><\/td>\n<td style=\"background-color: #ffffff; width: 120px;\" align=\"center\"><img decoding=\"async\" src=\"https:\/\/upload.wikimedia.org\/wikipedia\/commons\/thumb\/b\/b3\/Sj%C3%B6v%C3%A4gm%C3%A4rke%2C_Badplats.svg\/250px-Sj%C3%B6v%C3%A4gm%C3%A4rke%2C_Badplats.svg.png\" alt=\"\" width=\"99\"><\/td>\n<td style=\"background-color: #ffffff; width: 120px;\" align=\"center\"><a href=\"https:\/\/commons.wikimedia.org\/wiki\/File:Elevator_icon_arrows.png\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/upload.wikimedia.org\/wikipedia\/commons\/9\/98\/Elevator_icon_arrows.png\" alt=\"\" width=\"94\" height=\"94\"><\/a><\/td>\n<td style=\"background-color: #ffffff; width: 120px;\" align=\"center\">&nbsp;<\/td>\n<td style=\"background-color: #ffffff; width: 120px;\">&nbsp;<\/td>\n<\/tr>\n<tr>\n<td colspan=\"5\" style=\"background-color: #ffffff;\">\n<address>Verst\u00e4ndliche und weniger gelungene Piktogramme. Kannst du alle dekodieren? Wie k\u00f6nnten diese Piktogramme irrt\u00fcmlicherweise auch verstanden werden? (<a href=\"http:\/\/commons.wikimedia.org\/wiki\/Category:Public_information_symbols\" target=\"_blank\" rel=\"noopener\">weitere<\/a> Beispiele und Hinweise zu den Urheberrechten)<\/address>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<h1>Vorgeschichte<\/h1>\n<p>Ein Piktogramm (von lat.: pictum = gemalt, Bild; griech.: gr\u00e1phein = schreiben) ist ein Bildzeichen, das Information durch vereinfachte grafische Darstellung vermittelt. Sender k\u00f6nnen mit einem Piktogramm Informationen visuell zug\u00e4nglich kodieren, sodass Empf\u00e4nger die Botschaft einfach und schnell dekodieren und verstehen k\u00f6nnen. Piktogramme kennt man heute vor allem aus dem Strassenverkehr und von anderen Leitsystemen. Denn hier m\u00fcssen Informationen fehlerlos und rasch vermittelt werden. Als Vorl\u00e4ufer der heutigen, modernen Piktogramme k\u00f6nnen fr\u00fche Schriftsysteme wie z.B. <a href=\"http:\/\/de.wikipedia.org\/wiki\/%C3%84gyptische_Hieroglyphen\" target=\"_blank\" rel=\"noopener\">alt\u00e4gyptische Hieroglyphen<\/a> oder <a href=\"http:\/\/de.wikipedia.org\/wiki\/Chinesische_Schrift\" target=\"_blank\" rel=\"noopener\">chinesische Schriftzeichen<\/a> verstanden werden. Auch Zunftzeichen, Wirtschaftsschilder und die <a href=\"http:\/\/de.wikipedia.org\/wiki\/Heraldik\" target=\"_blank\" rel=\"noopener\">Heraldik<\/a>, also die Wappenlehre mit oftmals pr\u00e4zisen Regeln zur Gestaltung (Wappenkunst) und Rezeption (Wappenkunde, Lesen der Wappen), gelten unter anderem als Wegbereiter f\u00fcr die heutigen Piktogramme.<\/p>\n<h1>Das Piktogramm: eine medien\u00e4sthetische Erneuerung<\/h1>\n<p>Doch erst Anfangs des 20. Jahrhunderts gab es Bestrebungen zur Entwicklung von Piktogrammen, wie wir sie heute verstehen. Einen grossen Beitrag leisteten diesbez\u00fcglich der Wiener Sozialphilosoph <a href=\"https:\/\/de.wikipedia.org\/wiki\/Otto_Neurath\">Otto Neurath<\/a> zusammen mit dem Grafiker <a href=\"http:\/\/de.wikipedia.org\/wiki\/Gerd_Arntz\" target=\"_blank\" rel=\"noopener\">Gerd Arntz<\/a>. Sie entwickelten ca. ab 1925 die internationale Bildersprache und wissenschaftliche Informationsgrafik ISOTYPE (International System of Typographic Picture Education).<\/p>\n<p>Neurath und Arntz strebten mit ihrer ISOTYPE den rationalen und konsistenten Einsatz von Bildzeichen an. Sie setzten mit ihrer &#8222;Wiener Methode&#8220; unter anderem auf eine klare Farbsymbolik und eine hohe Gegenst\u00e4ndlichkeit trotz r\u00e4umlich reduzierter Darstellung z.B. durch &#8222;Scherenschnittformen&#8220; oder <a href=\"http:\/\/de.wikipedia.org\/wiki\/Axonometrie#Isometrische_Axonometrie\" target=\"_blank\" rel=\"noopener\">isometrische Darstellungen<\/a>. Sie wollten unter anderem keinen symbolischen Gegenstandsgehalt, keine Raumillusion, keine kreative Ausschm\u00fcckung, weder \u00dcberfeinerung noch sonst irgendwelche Willk\u00fcr im Bildzeichen. Sie wollten keine Illustration im engeren Sinne sondern Wissen vermitteln.<\/p>\n<h1>Der soziale Hintergrund<\/h1>\n<p>Dies hat einen sozialen und sozialpolitischen Hintergrund. Neurath: \u201eDer gew\u00f6hnliche B\u00fcrger sollte in der Lage sein, uneingeschr\u00e4nkt Informationen \u00fcber alle Gegenst\u00e4nde zu erhalten, die ihn interessieren, wie er geographisches Wissen von Karten und Atlanten erhalten kann&#8220;. ISOTYPE sollte \u201eWissen durch visuelle Mittel weitestm\u00f6glich mitzuteilen und dadurch die Kluft zwischen V\u00f6lkern und Sprachgruppen verringern zu helfen&#8220;. ISOTYPE war demnach ein Instrument zur&nbsp; &#8222;Humanisierung des Wissen&#8220;, sprich zur Demokratisierung von Wissen.<\/p>\n<h1>Weitere Eckpunkte bis heute<\/h1>\n<p>Im weiteren Verlauf des 20. Jahrhunderts wurden die Piktogramme durch neu ausgebaute Flugh\u00e4fen oder Grossanl\u00e4sse wie die Olympischen Spiele immer wieder weiter entwickelt und revolutioniert. So entwickelte z.B. der detusche Designer <a href=\"https:\/\/de.wikipedia.org\/wiki\/Otl_Aicher\">Otl Aicher<\/a> das einflussreiche, geometrische Piktogramm-System f\u00fcr die M\u00fcnchner Olympiade von 1972, das in formal\u00e4sthetischer Hinsicht zum Quasi-Standard avancierte. (Siehe zum Thema Olympiade weiter z.B. die etwas subjektiv eingef\u00e4rbte Geschichte der Piktogramme an den Olympischen Spielen vom Designer Steven <a href=\"http:\/\/www.hellerbooks.com\" target=\"_blank\" rel=\"noopener\">Heller<\/a> auf <a href=\"http:\/\/www.youtube.com\/watch?v=yHWlEU8zqUE&amp;feature=player_embedded\" target=\"_blank\" rel=\"noopener\">Youtube<\/a> f\u00fcr die NY Times)<\/p>\n<p>Im heutigen Zeitalter der Internationalisierung und Globalisierung sind Piktogramme f\u00fcr Leitsysteme, Produktkennzeichnungen und anderer weitl\u00e4ufiger Kommunikation unverzichtbar. Viele Piktogramme werden noch heute neu erfunden, andere hingegen sind bereits standardisiert. Die internationale Organisation f\u00fcr Standardisierung (ISO) versucht sogar nicht interkulturell verst\u00e4ndliche Piktogramme zu reduzieren.<\/p>\n<p>Piktogramme befinden sich heute als Selbstverst\u00e4ndlichkeit im Alltag eines Jeden und einer Jeden unserer globalisierten Welt. Piktogramme kommunizieren schnell, sprach\u00fcbergreifend und haben das geschafft, was mit&nbsp; internationalen Plansprachen wie die <a href=\"http:\/\/de.wikipedia.org\/wiki\/Esperanto#Kritik_und_Erwiderung\" target=\"_blank\" rel=\"noopener\">Esperanto<\/a> bis heute nicht gelungen ist. Mittlerweilen besch\u00e4ftigt sich auch die Bildende Kunst mit Piktogrammen, wie es z.B. bei <a href=\"http:\/\/lionni.com\/\" target=\"_blank\" rel=\"noopener\">Pippo Lionni<\/a> zu sehen ist.<\/p>","protected":false},"excerpt":{"rendered":"<p>Dieser Beitrag fasst kurz die Geschichte der Piktogramme zusammen. Angesprochen werden historische, soziale und gestalterische Aspekte.<\/p>\n","protected":false},"author":1,"featured_media":1802,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[18],"tags":[34,24],"class_list":["post-441","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geschichte","tag-grafikdesign-visuelle-kommunikation","tag-kunstgeschichte-bildwissenschaft"],"acf":[],"_links":{"self":[{"href":"https:\/\/kunstunterricht.ch\/e\/wp-json\/wp\/v2\/posts\/441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kunstunterricht.ch\/e\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kunstunterricht.ch\/e\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kunstunterricht.ch\/e\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kunstunterricht.ch\/e\/wp-json\/wp\/v2\/comments?post=441"}],"version-history":[{"count":4,"href":"https:\/\/kunstunterricht.ch\/e\/wp-json\/wp\/v2\/posts\/441\/revisions"}],"predecessor-version":[{"id":1805,"href":"https:\/\/kunstunterricht.ch\/e\/wp-json\/wp\/v2\/posts\/441\/revisions\/1805"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kunstunterricht.ch\/e\/wp-json\/wp\/v2\/media\/1802"}],"wp:attachment":[{"href":"https:\/\/kunstunterricht.ch\/e\/wp-json\/wp\/v2\/media?parent=441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kunstunterricht.ch\/e\/wp-json\/wp\/v2\/categories?post=441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kunstunterricht.ch\/e\/wp-json\/wp\/v2\/tags?post=441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}